{"id":19128,"date":"2025-10-16T08:38:23","date_gmt":"2025-10-16T08:38:23","guid":{"rendered":"https:\/\/muzeum.haus.pl\/?post_type=archiwistyka&#038;p=19128"},"modified":"2025-10-16T08:38:23","modified_gmt":"2025-10-16T08:38:23","slug":"michael-birawer","status":"publish","type":"archiwistyka","link":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/","title":{"rendered":"Michael Birawer"},"content":{"rendered":"<p>Geboren im Jahr 1803 in So\u015bnicowice, Sohn des P\u00e4chters Itzig Isaac (1756\/57\u201310.03.1831) und dessen Ehefrau Charlotta, geb. Singer. Wahrscheinlich erhielt er seinen Vornamen nach seinem Gro\u00dfvater v\u00e4terlicherseits. Neben Michael erreichten mindestens drei seiner Geschwister das Erwachsenenalter: die Schwestern Pauline (gest. 26.01.1874; unverheiratet, arbeitete in den 1850er Jahren als Hutmacherin \u2013 sie reinigte und reparierte Strohh\u00fcte sowie fertigte Hauben an) und Jeanette (1802\u201310.05.1893) sowie der Bruder Pinkus (02.01.1815 \u2013 01.12.1896), der Mitglied der Leitung der \u00f6rtlichen j\u00fcdischen Begr\u00e4bnisbruderschaft Chewra Kadisza war.<br \/>\nDie Eltern von Michael zogen sp\u00e4ter nach Gleiwitz. Dort erhielt Michael im Jahr 1829 das B\u00fcrgerrecht und f\u00fchrte ein Hotel mit angeschlossener Gastwirtschaft. Im Juli 1847 fand in diesem Saal eine Feier zur \u00dcbergabe der Fahne der \u00f6rtlichen Sch\u00fctzengilde statt. In der lokalen Presse wurde er im Jahr 1862 bereits als \u201eHotelbesitzer\u201c bezeichnet. Mitte des 19. Jahrhunderts war er Eigent\u00fcmer einer Immobilie in der Beuthenerstra\u00dfe 42, worauf eine Vermietungsanzeige in der Lokalpresse \u2013 ver\u00f6ffentlicht von Pinkus oder Pauline \u2013 hinweist. Dies ist insofern bemerkenswert, als es sich bei der Beuthenerstra\u00dfe um eine kurze Stra\u00dfe handelt. Die angegebene Adresse k\u00f6nnte darauf hindeuten, dass die Stra\u00dfe urspr\u00fcnglich mit einer anderen verbunden war, oder dass es sich um einen Druckfehler in der Anzeige handelt.<br \/>\nMichaels letzte Wohnadresse war das Haus in der Beuthenerstra\u00dfe 10 (heute ul. Bytomska) in Gleiwitz, wo er mit seiner Familie lebte. Er hatte vermutlich zwei Ehefrauen: die erste war Helena, geb. M\u00fcller (1808\u201323.06.1855), die an den Folgen einer starken Blutung verstarb, und Palmira, geb. Sachs, die im Jahr 1890 unter dieser Adresse koschere Lebensmittel zum Pessach-Fest verkaufte. \u00dcber Palmiras weiteres Schicksal ist bislang nichts bekannt \u2013 sie ist in keinem der beiden j\u00fcdischen Friedh\u00f6fe in Gleiwitz verzeichnet.<br \/>\nEr hatte mindestens zwei S\u00f6hne: Heinrich, der im Alter von nur 27 Jahren am 17.04.1862 an Tuberkulose verstarb, sowie Isaac (1832\u201306.02.1884). Isaac trat in die Fu\u00dfstapfen seines Vaters und war in den Jahren 1870 bis 1881 (vermutlich mit einer Unterbrechung zwischen 1878 und 1881) Eigent\u00fcmer des bekannten Gleiwitzer Hotels \u201eZur Goldenen Gans\u201c in der damaligen Tarnowitzerstra\u00dfe (heute ul. Matejki 3). Den Tod Michaels meldete das Standesamt durch Pinkus.<\/p>\n","protected":false},"featured_media":18841,"template":"","meta":{"_acf_changed":false},"class_list":["post-19128","archiwistyka","type-archiwistyka","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:description\" content=\"Geboren im Jahr 1803 in So\u015bnicowice, Sohn des P\u00e4chters Itzig Isaac (1756\/57\u201310.03.1831) und dessen Ehefrau Charlotta, geb. Singer. Wahrscheinlich erhielt er seinen Vornamen nach seinem Gro\u00dfvater v\u00e4terlicherseits. Neben Michael erreichten...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:image\" content=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Birawer_Michael_nagrobek-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/\",\"name\":\"Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Birawer_Michael_nagrobek-scaled.jpg\",\"datePublished\":\"2025-10-16T08:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Birawer_Michael_nagrobek-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Birawer_Michael_nagrobek-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Michael Birawer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/michael-birawer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archiv\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Michael Birawer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\",\"name\":\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"description\":\"DWPN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/","og_locale":"de_DE","og_type":"article","og_title":"Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_description":"Geboren im Jahr 1803 in So\u015bnicowice, Sohn des P\u00e4chters Itzig Isaac (1756\/57\u201310.03.1831) und dessen Ehefrau Charlotta, geb. Singer. Wahrscheinlich erhielt er seinen Vornamen nach seinem Gro\u00dfvater v\u00e4terlicherseits. Neben Michael erreichten...","og_url":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/","og_site_name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_image":[{"width":1920,"height":2560,"url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Birawer_Michael_nagrobek-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/","url":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/","name":"Michael Birawer - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","isPartOf":{"@id":"https:\/\/muzeum.haus.pl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/#primaryimage"},"image":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/#primaryimage"},"thumbnailUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Birawer_Michael_nagrobek-scaled.jpg","datePublished":"2025-10-16T08:38:23+00:00","breadcrumb":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/#primaryimage","url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Birawer_Michael_nagrobek-scaled.jpg","contentUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Birawer_Michael_nagrobek-scaled.jpg","width":1920,"height":2560,"caption":"Michael Birawer"},{"@type":"BreadcrumbList","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/michael-birawer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/muzeum.haus.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Archiv","item":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/"},{"@type":"ListItem","position":3,"name":"Michael Birawer"}]},{"@type":"WebSite","@id":"https:\/\/muzeum.haus.pl\/de\/#website","url":"https:\/\/muzeum.haus.pl\/de\/","name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","description":"DWPN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muzeum.haus.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/archiwistyka\/19128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/archiwistyka"}],"about":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/types\/archiwistyka"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media\/18841"}],"wp:attachment":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media?parent=19128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}