{"id":19144,"date":"2025-10-16T12:05:13","date_gmt":"2025-10-16T12:05:13","guid":{"rendered":"https:\/\/muzeum.haus.pl\/?post_type=archiwistyka&#038;p=19144"},"modified":"2025-10-16T12:05:13","modified_gmt":"2025-10-16T12:05:13","slug":"emma-kochmann-2","status":"publish","type":"archiwistyka","link":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/","title":{"rendered":"Emma Kochmann"},"content":{"rendered":"<p>Sie wurde am 19. Juli 1859 in Rybnik in einer j\u00fcdischen Familie geboren, als Tochter von Samuel (geb. am 1813, vermutlich gest. am 1894) und einer Mutter, deren Name unbekannt ist. Sie war die Ehefrau des Klempnermeisters Kochmann (vermutlich Adolf). W\u00e4hrend des Ersten Weltkriegs lebte sie in der Markgrafenstra\u00dfe 1 (heute ul. S. Wyszy\u0144skiego, die Hausnummer hat sich im Laufe der Jahre ge\u00e4ndert). Ihr letzter Wohnsitz war ein Mietshaus in der Keithstra\u00dfe 8 (heute ul. Zawiszy Czarnego 8), wo Emma im November 1933 verstarb. Aufgrund der damaligen politischen Lage (im Januar 1933 wurde Adolf Hitler Kanzler von Deutschland) erschien nach ihrem Tod in der \u201eDer Oberschlesische Wanderer\u201c \u2013 einer der meistgelesenen Zeitungen der Region \u2013 kein Nachruf. Die Todesanzeige wurde vom Standesamt durch Johanna Kochmann, geb. S\u00fcsskind \u2013 Emmas Schwiegertochter \u2013 gemeldet. Johanna teilte sp\u00e4ter das Schicksal von etwa 600 j\u00fcdischen Einwohnern aus Gleiwitz: Sie wurde in das sogenannte Judenhaus in der Nikolaistra\u00dfe 15 eingewiesen. Von dort aus wurde sie am 20. Mai 1942 in das Konzentrationslager Auschwitz-Birkenau deportiert, wo sie ermordet wurde.<\/p>\n","protected":false},"featured_media":18986,"template":"","meta":{"_acf_changed":false},"class_list":["post-19144","archiwistyka","type-archiwistyka","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:description\" content=\"Sie wurde am 19. Juli 1859 in Rybnik in einer j\u00fcdischen Familie geboren, als Tochter von Samuel (geb. am 1813, vermutlich gest. am 1894) und einer Mutter, deren Name unbekannt...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:image\" content=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Kochmann_Emma_2-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/\",\"name\":\"Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Kochmann_Emma_2-1-scaled.jpg\",\"datePublished\":\"2025-10-16T12:05:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Kochmann_Emma_2-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Kochmann_Emma_2-1-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Emma Kochmann\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/emma-kochmann-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archiv\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/archiwistyka\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Emma Kochmann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\",\"name\":\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"description\":\"DWPN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/","og_locale":"de_DE","og_type":"article","og_title":"Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_description":"Sie wurde am 19. Juli 1859 in Rybnik in einer j\u00fcdischen Familie geboren, als Tochter von Samuel (geb. am 1813, vermutlich gest. am 1894) und einer Mutter, deren Name unbekannt...","og_url":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/","og_site_name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_image":[{"width":1920,"height":2560,"url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Kochmann_Emma_2-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/","url":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/","name":"Emma Kochmann - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","isPartOf":{"@id":"https:\/\/muzeum.haus.pl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/#primaryimage"},"image":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/#primaryimage"},"thumbnailUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Kochmann_Emma_2-1-scaled.jpg","datePublished":"2025-10-16T12:05:13+00:00","breadcrumb":{"@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/#primaryimage","url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Kochmann_Emma_2-1-scaled.jpg","contentUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2025\/10\/Kochmann_Emma_2-1-scaled.jpg","width":1920,"height":2560,"caption":"Emma Kochmann"},{"@type":"BreadcrumbList","@id":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/emma-kochmann-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/muzeum.haus.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Archiv","item":"https:\/\/muzeum.haus.pl\/de\/archiwistyka\/"},{"@type":"ListItem","position":3,"name":"Emma Kochmann"}]},{"@type":"WebSite","@id":"https:\/\/muzeum.haus.pl\/de\/#website","url":"https:\/\/muzeum.haus.pl\/de\/","name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","description":"DWPN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muzeum.haus.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/archiwistyka\/19144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/archiwistyka"}],"about":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/types\/archiwistyka"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media\/18986"}],"wp:attachment":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media?parent=19144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}