{"id":17062,"date":"2021-11-10T11:04:29","date_gmt":"2021-11-10T11:04:29","guid":{"rendered":"https:\/\/muzeum.haus.pl\/wystawa\/wirtualna-wystawa-w-poszukiwaniu-dziadkow\/"},"modified":"2022-09-28T16:53:10","modified_gmt":"2022-09-28T16:53:10","slug":"virtuelle-ausstellung-auf-der-suche-nach-den-groseltern","status":"publish","type":"project","link":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/","title":{"rendered":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c"},"content":{"rendered":"<div id=\"cmsmasters_row_aubqooij48\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_80xxo4l8hp\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<figure id=\"attachment_16975\" aria-describedby=\"caption-attachment-16975\" style=\"width: 196px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01.jpg\" data-lbwps-width=\"1680\" data-lbwps-height=\"2574\" data-lbwps-srcsmall=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-196x300.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-16975\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-196x300.jpg\" alt=\"\" width=\"196\" height=\"300\" srcset=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-196x300.jpg 196w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-668x1024.jpg 668w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-768x1177.jpg 768w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-1003x1536.jpg 1003w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-1337x2048.jpg 1337w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-580x889.jpg 580w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-860x1318.jpg 860w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-1160x1777.jpg 1160w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-1320x2022.jpg 1320w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_01-scaled.jpg 1671w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><figcaption id=\"caption-attachment-16975\" class=\"wp-caption-text\">Janusz Ma\u0107kowiak und Ruta Mandelbaum, die Gro\u00dfeltern von Marta Ma\u0107kowiak<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Unsere Beziehungen zur Familie m\u00f6gen unterschiedlich sein, aber ohne Zweifel spielen sie eine \u00fcberaus wichtige Rolle bei der Herausbildung unserer Identit\u00e4t und unserer Wahrnehmung der Welt. Dies gilt sowohl f\u00fcr Bindungen zu lebenden Verwandten als auch zu Vorfahren, die wir niemals kennenlernen konnten.<\/p>\n<p style=\"font-weight: 400;\">Von ihnen haben wir nicht nur Aussehen, Charakter, Talente oder Interessen geerbt. Wir tragen die Geschichten unserer Eltern, Gro\u00dfeltern und vorheriger Generationen in uns. Und diese \u2013 die freudigen wie die tragischen \u2013 beeinflussen unser Leben, unsere Entscheidungen und \u00dcberzeugungen. Indem wir die Biografien unserer Vorfahren entdecken, k\u00f6nnen wir vor allem etwas \u00fcber uns selbst lernen. In den Geschichten unserer Familienangeh\u00f6rigen k\u00f6nnen wir sich wiederholende Muster erkennen, uns von ihnen befreien und beginnen, unsere eigene Geschichte zu schreiben.<\/p>\n<p style=\"font-weight: 400;\">Die Ausstellung \u201eAuf der Suche nach den Gro\u00dfeltern\u201c besch\u00e4ftigt sich mit dem Thema der Entdeckung der eigenen Identit\u00e4t und zeigt, warum es sich lohnt, Familiengeschichten zu erkunden. Die Autorin l\u00e4sst uns an ihren Erfahrungen teilhaben, zeigt die Besonderheiten der Arbeit der Ahnenforschung auf und ermuntert dazu, einen eigenen Stammbaum zu erstellen.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Zapowied\u017a wystawy: &#8222;W poszukiwaniu dziadk\u00f3w &#8230; &#8222;<\/p>\n","protected":false},"author":1,"featured_media":16941,"parent":0,"menu_order":113,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17062","project","type-project","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:description\" content=\"Zapowied\u017a wystawy: &quot;W poszukiwaniu dziadk\u00f3w ... &quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T16:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/06\/w-posz-dziadkow-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1659\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/\",\"name\":\"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/w-posz-dziadkow-scaled.jpg\",\"datePublished\":\"2021-11-10T11:04:29+00:00\",\"dateModified\":\"2022-09-28T16:53:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/w-posz-dziadkow-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/muzeum.haus.pl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/w-posz-dziadkow-scaled.jpg\",\"width\":1659,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ausstellung\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\",\"name\":\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"description\":\"DWPN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/","og_locale":"de_DE","og_type":"article","og_title":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_description":"Zapowied\u017a wystawy: \"W poszukiwaniu dziadk\u00f3w ... \"","og_url":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/","og_site_name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","article_modified_time":"2022-09-28T16:53:10+00:00","og_image":[{"width":1659,"height":2560,"url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/06\/w-posz-dziadkow-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/","url":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/","name":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","isPartOf":{"@id":"https:\/\/muzeum.haus.pl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/#primaryimage"},"image":{"@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/#primaryimage"},"thumbnailUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/06\/w-posz-dziadkow-scaled.jpg","datePublished":"2021-11-10T11:04:29+00:00","dateModified":"2022-09-28T16:53:10+00:00","breadcrumb":{"@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/#primaryimage","url":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/06\/w-posz-dziadkow-scaled.jpg","contentUrl":"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/06\/w-posz-dziadkow-scaled.jpg","width":1659,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/muzeum.haus.pl\/de\/"},{"@type":"ListItem","position":2,"name":"ausstellung","item":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/"},{"@type":"ListItem","position":3,"name":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c"}]},{"@type":"WebSite","@id":"https:\/\/muzeum.haus.pl\/de\/#website","url":"https:\/\/muzeum.haus.pl\/de\/","name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","description":"DWPN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muzeum.haus.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17062\/revisions"}],"predecessor-version":[{"id":17064,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17062\/revisions\/17064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media\/16941"}],"wp:attachment":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media?parent=17062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}