{"id":17075,"date":"2022-09-26T14:44:48","date_gmt":"2022-09-26T14:44:48","guid":{"rendered":"https:\/\/muzeum.haus.pl\/wystawa\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/praca-genealoga-praca-genealozki\/"},"modified":"2022-10-04T06:37:22","modified_gmt":"2022-10-04T06:37:22","slug":"die-arbeit-des-genealogen-der-genealogin","status":"publish","type":"project","link":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/","title":{"rendered":"Die Arbeit der Genealog*innen"},"content":{"rendered":"<div id=\"cmsmasters_row_bkrqerlwx6\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_f4duwgmvn\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p style=\"font-weight: 400;\">Die Arbeit von GenealogInnen wird von den einen mit dem Aufdecken von Familiengeheimnissen und von anderen mit langen in Archiven und vor dem Computer verbrachten Stunden assoziiert. In Wirklichkeit kombiniert man das eine mit dem anderen und es ist sicherlich kein typischer Job von acht bis sechzehn Uhr. Jeder Ahnenforscher (egal ob Profi oder Amateur) wird zugeben, dass man bei der Suche leicht die Zeit aus den Augen verliert und dass die Freude \u00fcber die gefundenen Informationen und Dokumente f\u00fcr alle M\u00fchen entsch\u00e4digt.<\/p>\n<p style=\"font-weight: 400;\">Das Hauptziel des Genealogen ist es, einen Stammbaum zu erstellen, also zu den \u00e4ltesten Generationen vorzudringen und auch Verwandte aus Seitenlinien zu identifizieren, falls dies gew\u00fcnscht wird. Bei der Entdeckung von Familiengeschichten erfahren wir auch etwas \u00fcber die Heimatgeschichte einer Ortschaft oder Region sowie \u00fcber die Gepflogenheiten der jeweiligen Zeit. Der Umfang der Suche h\u00e4ngt andererseits immer von den Erwartungen und Bedarfen ab \u2013 so kann es sein, dass manche Menschen Informationen zur Familie nur von einer Seite her aufsp\u00fcren m\u00f6chten, oder dass es ihnen darum geht, eine geheimnisumwitterte Familienlegende zu best\u00e4tigen.<\/p>\n<\/div>\n<div id=\"cmsmasters_gallery_hjhdm18g9v\" class=\"cmsmasters_gallery_wrap\" data-type=\"grid\" data-count=\"0\"><ul class=\"cmsmasters_gallery cmsmasters_2 cmsmasters_more_items_loader\"><li id=\"rzecz_17009\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_09-scaled.jpg\" data-caption=\"Danusia Pud\u0142o, geb. Kaleta\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_09-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>Danusia Pud\u0142o, geb. Kaleta<\/figcaption><\/figure><\/li><li id=\"rzecz_17011\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_10-scaled.jpg\" data-caption=\"Studienbuch von Ruta Mandelbaum am Warschauer Polytechnikum\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_10-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>Studienbuch von Ruta Mandelbaum am Warschauer Polytechnikum<\/figcaption><\/figure><\/li><\/ul><\/div>\n<div id=\"cmsmasters_divider_k8r51ibyga\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div id=\"cmsmasters_heading_53fsgtepdk\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h2 class=\"cmsmasters_heading\">Detektivischer Sp\u00fcrsinn<\/h2>\n<\/div><div class=\"cmsmasters_text\">\n<p style=\"font-weight: 400;\">Die Arbeit von Ahnenforschern kann an eine Detektivrecherche erinnern \u2013 sie umfasst die Befragung, Nachforschungen, die \u00dcberpr\u00fcfung verschiedener Hinweise und die Aufdeckung neuer, oft \u00fcberraschender Fakten. Hilfreich ist sicherlich die F\u00e4higkeit, die richtigen Fragen zu stellen und die richtigen Hypothesen aufzustellen. Man muss in der Lage sein, Zusammenh\u00e4nge zu erkennen, die eingeholten Informationen zu \u00fcberpr\u00fcfen und auf seine Intuition zu h\u00f6ren, die sich oft als unbezahlbar erweist. Wichtig sind auch Geschichtswissen, Vertrautheit mit einstigen Gepflogenheiten, Sprachkenntnisse (Deutsch, Polnisch, Russisch etc.), die F\u00e4higkeit schwer leserliche alte Handschriften in diesen Sprachen und in Latein zu entschl\u00fcsseln. Zum Gl\u00fcck wird das Auge mit der Zeit geschulter, und jeder weitere Text bereitet immer geringere Schwierigkeiten.<\/p>\n<\/div>\n<div id=\"cmsmasters_gallery_z43oxpdl1j\" class=\"cmsmasters_gallery_wrap\" data-type=\"grid\" data-count=\"0\"><ul class=\"cmsmasters_gallery cmsmasters_2 cmsmasters_more_items_loader\"><li id=\"rzecz_17016\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_11.jpg\" rel=\"ilightbox[z43oxpdl1j]\" data-caption=\"Ausschnitt aus einem Artikel der Tageszeitung \u201eKurier Warszawski\u201c (7.08.1938) \u00fcber die beliebte Betrugsmethode \u201eKonsul-Trick\u201c\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_11-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>Ausschnitt aus einem Artikel der Tageszeitung \u201eKurier Warszawski\u201c (7.08.1938) \u00fcber die beliebte Betrugsmethode \u201eKonsul-Trick\u201c<\/figcaption><\/figure><\/li><li id=\"rzecz_17018\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_12.jpg\" rel=\"ilightbox[z43oxpdl1j]\" data-caption=\"Erfassungsfoto von Abram Lejb \u201eMojsie\u201c Wester (Trickbetr\u00fcger, der mit der \u201eKonsul-Methode\u201c arbeitete) aus der Personalakte der Ermittlungsbeh\u00f6rde der Hauptstadt Warschau 1927\u20131948, Staatsarchiv Warschau\"><img loading=\"lazy\" decoding=\"async\" width=\"464\" height=\"320\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_12.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" srcset=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_12.jpg 464w, https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_12-300x207.jpg 300w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/a><figcaption>Erfassungsfoto von Abram Lejb \u201eMojsie\u201c Wester (Trickbetr\u00fcger, der mit der \u201eKonsul-Methode\u201c arbeitete) aus der Personalakte der Ermittlungsbeh\u00f6rde der Hauptstadt Warschau 1927\u20131948, Staatsarchiv Warschau<\/figcaption><\/figure><\/li><\/ul><\/div>\n<div id=\"cmsmasters_divider_7oktc35jy\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div id=\"cmsmasters_heading_oovw4bhg09\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h2 class=\"cmsmasters_heading\">Empathischer Zugang<\/h2>\n<\/div><div class=\"cmsmasters_text\">\n<p style=\"font-weight: 400;\">Einf\u00fchlungsverm\u00f6gen und Aufgeschlossenheit sind bei der Arbeit an Familiengeschichten unabdingbar. Manche Kunden versuchen, eine unangenehme Vergangenheit aufzudecken, mit der sie wahrscheinlich als erste in der Familie werden zurechtkommen m\u00fcssen. Andere finden erst im Laufe der Recherche heikle Fakten heraus und m\u00fcssen sich ihnen stellen. F\u00fcr die meisten Menschen ist die Aufarbeitung der Familiengeschichte ein intimer Prozess, bei dem bestimmte Dinge zum ersten Mal laut ausgesprochen werden.<\/p>\n<p style=\"font-weight: 400;\">Daher ist es gut, einen sicheren Raum zu schaffen, die Daten privat zu halten und dem Gegen\u00fcber die M\u00f6glichkeit zu geben, sich zu \u00f6ffnen. Manchmal ist eine zentrale Geschichte oder ein Teil des Lebens verdr\u00e4ngt und vergessen worden. Zum Gl\u00fcck k\u00f6nnen wir mit Geduld und richtig gestellten Fragen die Vorstellungskraft anregen und neue Antworten erhalten.<\/p>\n<\/div>\n<div id=\"cmsmasters_gallery_40jip9yf5\" class=\"cmsmasters_gallery_wrap\" data-type=\"grid\" data-count=\"0\"><ul class=\"cmsmasters_gallery cmsmasters_2 cmsmasters_more_items_loader\"><li id=\"rzecz_16986\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_06.jpg\" rel=\"ilightbox[40jip9yf5]\" data-caption=\"Ignacy Ma\u0107kowiak und Helena, geb. Kazi\u0144ska\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_06-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>Ignacy Ma\u0107kowiak und Helena, geb. Kazi\u0144ska<\/figcaption><\/figure><\/li><li id=\"rzecz_16988\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_07.jpg\" rel=\"ilightbox[40jip9yf5]\" data-caption=\"W\u0142adys\u0142aw und Bronis\u0142awa Kaleta, Grodzan\u00f3w\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_07-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>W\u0142adys\u0142aw und Bronis\u0142awa Kaleta, Grodzan\u00f3w<\/figcaption><\/figure><\/li><\/ul><\/div>\n<div id=\"cmsmasters_divider_881dm8l5h9\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center b-hr\"><\/div>\n<div id=\"cmsmasters_heading_n9n5eqdypw\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h2 class=\"cmsmasters_heading\">Die Arbeit mit der suchenden Person<\/h2>\n<\/div><div class=\"cmsmasters_text\">\n<p style=\"font-weight: 400;\">Eine genealogische Recherche ist ein Prozess, der immer mit einem Gespr\u00e4ch, einem kurzen Interview mit dem Suchenden beginnt. W\u00e4hrend des Gespr\u00e4chs frage ich nach wichtigen Informationen wie Vor- und Nachnamen, Geburtsdaten und -orten und anderen zus\u00e4tzlichen Fakten, die sich bei der Suche als entscheidend erweisen k\u00f6nnten. Das k\u00f6nnen Familienlegenden sein oder besondere Erinnerungen, zum Beispiel Details \u00fcber das Aussehen des Elternhauses oder Beziehungen zwischen Familienmitgliedern, Informationen \u00fcber einen vermissten Onkel oder eine Geschichte \u00fcber verlorenes Eigentum.<\/p>\n<p style=\"font-weight: 400;\">In jedem Ger\u00fccht steckt ein K\u00f6rnchen Wahrheit, und genauso k\u00f6nnen von Generation zu Generation weitergegebene Mythen, auch wenn sie nicht komplett wahr sind, bei der Spurensuche den Weg in die richtige Richtung weisen.<\/p>\n<p style=\"font-weight: 400;\">Sobald ich die Grundinformationen habe, erstelle ich den Umriss des Stammbaums. Ich verzeichne alle Daten auf einem Blatt Papier, um so die famili\u00e4ren Beziehungen besser erkennen zu k\u00f6nnen. Ich stelle Wohnort, Konfessions- und Gemeindezugeh\u00f6rigkeit der Familie fest und pr\u00fcfe die Verf\u00fcgbarkeit und den Erhaltungszustand der Dokumente.<\/p>\n<p style=\"font-weight: 400;\">Davon h\u00e4ngt der weitere Verlauf der Arbeit ab \u2013 ob ich mit online gestellten Scans arbeite, in die Archive gehe oder beides tue. Nach der Genehmigung des Arbeitsplans durch den Kunden beginne ich mit der Recherche. Ich arbeite normalerweise in mehreren Phasen. Im Laufe der Suche kann sich herausstellen, dass ein bestimmtes Jahrbuch fehlt, es L\u00fccken in den Akten gibt oder die Vorfahren aus einer anderen Gemeinde zu ihrem sp\u00e4teren Wohnort zugewandert sind. Daher ist es am besten, mit der Methode kleiner Schritte zu arbeiten.<\/p>\n<p style=\"font-weight: 400;\">Die Recherche kann einen Monat dauern oder auch mehrere Jahre \u2013 je nach den Erwartungen sowie der Verf\u00fcgbarkeit und dem Erhaltungszustand der Dokumente. Und die Ergebnisse k\u00f6nnen variieren. Jede Familiengeschichte ist einzigartig, daher kann man kaum schematisch vorgehen. Es ist auch nicht immer m\u00f6glich, die genauen Ergebnisse vorherzusagen \u2013 manchmal wird das Ergebnis der Suche eine angenehme \u00dcberraschung sein, ein anderes Mal ein Schock. In einer Familie sto\u00dfen wir auf Vorfahren, die im 17. Jahrhundert gelebt haben, oder best\u00e4tigen eine vermutete adelige Herkunft. In einem anderen Fall erfahren wir von einem schrecklichen Unfall oder bleiben an einer Generation von Urgro\u00dfeltern h\u00e4ngen, wenn wir herausfinden, dass etwa ein Vorfahre einer unehelichen Verbindung entstammte.<\/p>\n<p style=\"font-weight: 400;\">Bei Beginn der Suche lohnt es sich, die Erwartungen los- und sich auf verschiedene Szenarien einzulassen.<\/p>\n<\/div>\n<div id=\"cmsmasters_divider_edgv9nhkb7\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center b-hr\"><\/div>\n<div id=\"cmsmasters_heading_mltpymcncd\" class=\"cmsmasters_heading_wrap cmsmasters_heading_align_left\">\n\t<h2 class=\"cmsmasters_heading\">Mit anderen Menschen arbeiten<\/h2>\n<\/div><div class=\"cmsmasters_text\">\n<p style=\"font-weight: 400;\">Die Arbeit eines Genealogen (Ahnenforschers) besteht nicht nur darin, Dokumente zu sichten, Informationen zu analysieren und einen Stammbaum zu erstellen. Es ist in erster Linie der Kontakt mit einem anderen Menschen, Begegnung mit den Ahnen und Herstellung einer Beziehung zu ihnen. Wir entdecken ihre Namen, finden heraus, wie und wo sie lebten. Wir begleiten sie sowohl in freudigen Momenten, wie der Geburt eines lang ersehnten Kindes, als auch in Momenten des Grauens, wenn wir ihre Kriegsschicksale verfolgen. Es ist eine kreative Arbeit, bei der sich mit einem unverbrauchten Blick, Aufgeschlossenheit und Einf\u00fchlungsverm\u00f6gen Wunder bewirken lassen. Genealogische Recherchen erm\u00f6glichen es uns nicht nur, herauszufinden, woher wir kommen und wie unsere Vorfahren hie\u00dfen. Sie erlauben uns, die Geschichte eines Ortes kennenzulernen und die kulturelle Vielfalt des Landes zu sp\u00fcren, w\u00e4hrend die Entdeckung von Familiengeheimnissen auch die M\u00f6glichkeit bietet, sich seinen eigenen D\u00e4monen zu stellen.<\/p>\n<\/div>\n<div id=\"cmsmasters_gallery_atnf09csp\" class=\"cmsmasters_gallery_wrap\" data-type=\"grid\" data-count=\"0\"><ul class=\"cmsmasters_gallery cmsmasters_1 cmsmasters_more_items_loader\"><li id=\"rzecz_17020\" class=\"cmsmasters_gallery_item cmsmasters_caption\"><figure><a href=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_13-scaled.jpg\" rel=\"ilightbox[atnf09csp]\" data-caption=\"Friedhof in Nowe Miasto nad Wart\u0105 (an der Warthe)\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"420\" src=\"https:\/\/muzeum.haus.pl\/wp-content\/uploads\/2022\/09\/w_poszukiwaniu_dziadkow_foto_13-580x420.jpg\" class=\"attachment-cmsmasters-project-thumb size-cmsmasters-project-thumb\" alt=\"\" \/><\/a><figcaption>Friedhof in Nowe Miasto nad Wart\u0105 (an der Warthe)<\/figcaption><\/figure><\/li><\/ul><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":17062,"menu_order":115,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17075","project","type-project","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T06:37:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/die-arbeit-des-genealogen-der-genealogin\\\/\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/die-arbeit-des-genealogen-der-genealogin\\\/\",\"name\":\"Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\"},\"datePublished\":\"2022-09-26T14:44:48+00:00\",\"dateModified\":\"2022-10-04T06:37:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/die-arbeit-des-genealogen-der-genealogin\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/die-arbeit-des-genealogen-der-genealogin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/die-arbeit-des-genealogen-der-genealogin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ausstellung\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c\",\"item\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/ausstellung\\\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Die Arbeit der Genealog*innen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/\",\"name\":\"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej\",\"description\":\"DWPN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muzeum.haus.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/","og_locale":"de_DE","og_type":"article","og_title":"Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","og_url":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/","og_site_name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","article_modified_time":"2022-10-04T06:37:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/","url":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/","name":"Die Arbeit der Genealog*innen - Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","isPartOf":{"@id":"https:\/\/muzeum.haus.pl\/de\/#website"},"datePublished":"2022-09-26T14:44:48+00:00","dateModified":"2022-10-04T06:37:22+00:00","breadcrumb":{"@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/die-arbeit-des-genealogen-der-genealogin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/muzeum.haus.pl\/de\/"},{"@type":"ListItem","position":2,"name":"ausstellung","item":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/"},{"@type":"ListItem","position":3,"name":"Virtuelle Ausstellung: \u201eAuf der Suche nach den Gro\u00dfeltern\u201c","item":"https:\/\/muzeum.haus.pl\/de\/ausstellung\/virtuelle-ausstellung-auf-der-suche-nach-den-groseltern\/"},{"@type":"ListItem","position":4,"name":"Die Arbeit der Genealog*innen"}]},{"@type":"WebSite","@id":"https:\/\/muzeum.haus.pl\/de\/#website","url":"https:\/\/muzeum.haus.pl\/de\/","name":"Muzeum online Domu Wsp\u00f3\u0142pracy Polsko-Niemieckiej","description":"DWPN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muzeum.haus.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17075\/revisions"}],"predecessor-version":[{"id":17121,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17075\/revisions\/17121"}],"up":[{"embeddable":true,"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/project\/17062"}],"wp:attachment":[{"href":"https:\/\/muzeum.haus.pl\/de\/wp-json\/wp\/v2\/media?parent=17075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}